{"id":36779,"date":"2026-06-19T13:03:13","date_gmt":"2026-06-19T17:03:13","guid":{"rendered":"https:\/\/www.ea.aw\/pages\/?p=36779"},"modified":"2026-07-09T13:14:22","modified_gmt":"2026-07-09T17:14:22","slug":"saa-ta-introduci-starttraject-pa-logra-mavo-diploma-den-2-ana","status":"publish","type":"post","link":"https:\/\/www.ea.aw\/pages\/saa-ta-introduci-starttraject-pa-logra-mavo-diploma-den-2-ana\/","title":{"rendered":"SAA ta introduci &#8216;starttraject&#8217; pa logra MAVO diploma den 2 a\u00f1a"},"content":{"rendered":"<p>Stichting Avondonderwijs Aruba (SAA) ta introduci un maneho nobo pa a\u00f1a escolar 2026-2027: Ta introduci <em>\u2018starttraject\u2019<\/em> pa por logra MAVO diploma den 2 a\u00f1a.<\/p>\n<p><!--more--><\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-36781\" src=\"https:\/\/www.ea.aw\/pages\/wp-content\/uploads\/2026\/06\/minkojis-2026-06-19-SAA-Mavo.jpg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"https:\/\/www.ea.aw\/pages\/wp-content\/uploads\/2026\/06\/minkojis-2026-06-19-SAA-Mavo.jpg 1536w, https:\/\/www.ea.aw\/pages\/wp-content\/uploads\/2026\/06\/minkojis-2026-06-19-SAA-Mavo-768x512.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<hr \/>\n<p>Stichting Avondonderwijs Aruba (SAA \u2013 AvondMAVO), cu tin como meta principal pa ofrece adulto- y hobennan un di dos oportunidad pa obtene nan diploma di MAVO den un structura educativo, husto, motivante y efectivo, a anuncia un cambio structural grandi den su maneho pa e a\u00f1a escolar 2026-2027. Cu e obhetivo pa reduci e cantidad halto di studiante cu ta stop cu nan estudio y pa engrandece e exito den estudio, e scol a dicidi di introduci un <em>\u2018Starttraject\u2019<\/em> (trayecto di inicio) innovador.<\/p>\n<p>E decision aki ta basa riba evaluacionnan reciente y un analisis di dato profundo, cual a mustra cu <em>Leerjaar 2<\/em>\u00a0tabata tin un porcentahe structuralmente halto di <em>uitval<\/em> (studiantenan cu ta bandona scol). Tradicionalmente, despues di e transicion di <em>\u2018fasttrack\u2019<\/em> y e studiantenan cu ta stop durante a\u00f1a, un tercera parti (1\/3) so di e grupo original tabata resta of pasa pa e siguiente nivel. Esaki tabata nifica un rendimento hopi abou, locual a boga pa un revision fundamental di e structura actual y pa un guia mas intensivo pa e studiantenan.<\/p>\n<hr \/>\n<h3><span style=\"color: #333333;\">Un chens husto pa tur studiante pa medio di e \u2018Starttraject\u2019<\/span><\/h3>\n<p>E <em>\u2018Starttraject\u2019<\/em> nobo lo cuminsa hunto cu e a\u00f1a escolar y lo dura te cu fin di november. Durante e periodo aki, tur studiante lo ricibi les directamente riba e nivel di <em>Leerjaar 3<\/em>, combina cu un (1) ora di <em>remedi\u00ebring<\/em> (guia y apoyo adicional) structuralmente inlcui den e orario paralelo pa tur studiante di e trayecto aki. Di e forma aki, e studiantenan ta ha\u00f1a un oportunidad husto pa demostra cu nan por maneha e nivel di MAVO, sin cu nan admision ta depende di un test di entrada (<em>instaptoets<\/em>), cual a wordo elimina pasobra e maneho nobo aki ta haci esaki innecesario. E unico rekisito di admision pa drenta e trayecto aki ta cu e studiante mester tin un edad minimo di 16 a\u00f1a.<\/p>\n<p>Na cuminsamento di december, e studiantenan cu cumpli cu e normanan di promocion stipula lo por pasa oficialmente pa <em>Leerjaar 3<\/em>. E normanan aki ta inclui: saca maximo un 5 (of dos 5 cu dos punto di compensacion), obtene e certificado di informatica, mantene un presencia minimo di 80% den les, y ricibi un conseho positivo di e docentenan. E studiantenan cu no logra e nivel rekeri na december por opta pa un trayecto di <em>remedi\u00ebring<\/em> special entre januari y april, structuralmente dise\u00f1a pa yuda nan pa toch por wordo admiti como studiante regular den e siguiente a\u00f1a escolar. Pa e prome a\u00f1a di implementacion, AvondMAVO a stipula un meta concreto cu por lo menos 40% di e studiantenan di e <em>\u2018Starttraject\u2019<\/em> mester pasa exitosamente pa <em>Leerjaar 3<\/em>.<\/p>\n<hr \/>\n<h3><span style=\"color: #333333;\">Cambio den maneho di dispensacion (vrijstellingen)<\/span><\/h3>\n<p>Den cuadro di e maneho nobo pa 2026-2027, AvondMAVO Aruba ta ahusta tambe e maneho di dispensacion pa materianan den <em>Leerjaar 3<\/em>. Anteriormente, un studiante por a haya dispensacion pa un materia pa e duracion di un a\u00f1a escolar so si el a saca un 7 of mas halto den e a\u00f1a anterior. Entrante e maneho nobo, e studiante lo por ha\u00f1a dispensacion caba ora e saca un 6, y e dispensacion aki lo ta valido pa dies (10) a\u00f1a. Cu esaki, ta trece e maneho di <em>Leerjaar 3<\/em> den li\u00f1a cu e maneho existente di certificado di <em>Leerjaar 4<\/em>. E cambio aki tin como meta principal pa motiva e studiantenan pa sigui cu nan estudio, evitando cu nan ta sinti nan mes demotiva pa ripiti un materia unda nan a demostra caba di tin e nivel rekeri. Directiva di scol lo asumi un rol crucial den guia y conseha e studiantenan den e escogencia aki pa percura cu esaki ta cuadra miho cu nan perspectiva personal di examen.<\/p>\n<p>Cu e cambionan aki, AvondMAVO Aruba ta scoge pa un entrada mas realista, motivante y enfoca riba resultadonan concreto. Manera directiva ta se\u00f1ala den su plan di maneho: <em>\u201cCambio ta dificil na principio, complica den e fase intermedio, pero bunita na final\u201d<\/em>. E enfoke nobo aki ta cuadra miho cu e grupo como meta, ta engrandece e oportunidad pa progresa y ta reduci e abandono escolar structural, mientras ta mantene e calidad halto di educacion.<\/p>\n<hr \/>\n<p><em>Fuente:\u00a0<\/em><em><a href=\"https:\/\/futuroaruba.com\/noticia\/\" target=\"_blank\" rel=\"noopener\">Website<\/a> <\/em><\/p>\n<p><em>Social media: <a href=\"https:\/\/www.facebook.com\/gerlienluzdianecroes\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a> \/ <a href=\"https:\/\/www.instagram.com\/gerliencroes\/\" target=\"_blank\" rel=\"noopener noreferrer\">Instagram<\/a>\u00a0<\/em><\/p>\n<hr \/>\n<h3><span style=\"color: #333333;\">Info \/ Contact<\/span><\/h3>\n<p>Pa mas informacion por busca den e alfabet menu riba pagina principal:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.ea.aw\/pages\/organisacion\/ministerio-di-ensenansa\/\">[M] Ministerio di Ense\u00f1ansa<\/a><\/li>\n<\/ul>\n<p>Por tuma contacto cu:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.ea.aw\/pages\/contact\/ministerio-di-ensenansa\/\">Ministerio di Ense\u00f1ansa<\/a><\/li>\n<li><a href=\"https:\/\/banstudia.com\/\" target=\"_blank\" rel=\"noopener\">Ban Studia<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Stichting Avondonderwijs Aruba (SAA) ta introduci un maneho nobo pa a\u00f1a escolar 2026-2027: Ta introduci \u2018starttraject\u2019 pa por logra MAVO diploma den 2 a\u00f1a.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[316,109,307,249,106],"class_list":["post-36779","post","type-post","status-publish","format-standard","hentry","category-news","tag-avond","tag-mavo","tag-minkojis","tag-minond","tag-secundario"],"_links":{"self":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts\/36779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/comments?post=36779"}],"version-history":[{"count":5,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts\/36779\/revisions"}],"predecessor-version":[{"id":36785,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts\/36779\/revisions\/36785"}],"wp:attachment":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/media?parent=36779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/categories?post=36779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/tags?post=36779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}