{"id":34478,"date":"2024-10-17T15:58:05","date_gmt":"2024-10-17T19:58:05","guid":{"rendered":"http:\/\/www.ea.aw\/pages\/?p=34478"},"modified":"2024-11-26T16:03:04","modified_gmt":"2024-11-26T20:03:04","slug":"arubahuis-ta-reuni-cu-organisacion-di-studiante","status":"publish","type":"post","link":"https:\/\/www.ea.aw\/pages\/arubahuis-ta-reuni-cu-organisacion-di-studiante\/","title":{"rendered":"Arubahuis ta reuni cu organisacion di Studiante"},"content":{"rendered":"<p>Gabinete di Minister Plenipotenciario na Hulanda (Arubahuis) recientemente a tene un reunion cu diferente organisacion di studiante na Hulanda.<\/p>\n<p><!--more--><\/p>\n<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\"><\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<p>Meta di e reunion aki tabata pa conoce otra mihor y intercambia riba topiconan cu ta interesante pa tanto e organisacionnan como Gabinete di Aruba.<\/p>\n<\/div>\n<p>E programa a cuminsa cu un introduccion di e organisacionnan den cual nan a papia riba nan metanan pa studiantenan y riba cual terenonan ta organisa actividadnan.<\/p>\n<p>Directora di Gabinete di Aruba Joselin Croes LL.M\/M.Sc a guia e session cu a consisti di algun preguntanan manera nan contacto cu Gabinete di Aruba, contacto cu e grupo di mentornan. Sra. Croes tambe a puntra e organisacionnan cual tabata nan actividad\/evenemento mas exitoso den e ultimo a\u00f1anan, con grandi e publico tabata ta y con a logra pa haya asina hopi hende. Otro punto cu tambe a keda lansa na e organisacionnan ta ki tipo di actividad e organisacionnan ta mira cu por wordo organisa en cooperacion cu Gabinete di Aruba. Importante pa sa ta cual temanan ta interesante pa studiantenan. Esaki en conneccion cu workshops cu Gabinete di Aruba ta pensa pa organisa.<\/p>\n<p>Minister Plenipotenciario demisionario mr. Ady Thijsen a bisa di ta contento cu hopi organisacion di studiantenan a bin na e encuentro aki. E mandatario a bisa cu Gabinete di Aruba a bin ta organisando diferente reunionnan cu studiantenan pa tende kico ta biba cerca nan y con Gabinete di Aruba por duna un aporte cu por contribui na e exito den nan estudio. Mescos cu e grupo di studiante ta na su lugar pa papia tambe cu e organisacionnan di studiante pa mira ki tipo di cooperacion por bin entre e organisacionnan y Gabinete di Aruba.<\/p>\n<p>Sr. Thijsen a bisa cu guia di studiante ta keda un trabao importante pa Gabinete di Aruba y tambe estrecha e contacto cu studiantenan Arubiano pa asina tambe sondea e posibilidad y animo bou di nos hobennan pa despues di a caba cu nan estudio, nan regresa Aruba pa contribui na bienestar y progreso di Aruba.<\/p>\n<hr \/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34479\" src=\"https:\/\/www.ea.aw\/pages\/wp-content\/uploads\/2024\/11\/AH-2024-10-17-Organisacion-Studiante-.jpg\" alt=\"\" width=\"745\" height=\"467\" \/><\/p>\n<hr \/>\n<h3><span style=\"color: #333333;\">Info<\/span><\/h3>\n<ul>\n<li><a href=\"https:\/\/www.ea.aw\/pages\/studia-na-hulanda\/\">[S] Studia na Hulanda<\/a><\/li>\n<\/ul>\n<hr \/>\n<h3><span style=\"color: #333333;\">Contact<\/span><\/h3>\n<ul>\n<li><a href=\"https:\/\/www.ea.aw\/pages\/contact\/arubahuis\/\">Kabinet van de Gevolmachtigde Minister van Aruba in Den Haag (Arubahuis)<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Gabinete di Minister Plenipotenciario na Hulanda (Arubahuis) recientemente a tene un reunion cu diferente organisacion di studiante na Hulanda.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[68,35,194,94],"class_list":["post-34478","post","type-post","status-publish","format-standard","hentry","category-news","tag-arubahuis","tag-arubalening","tag-duo","tag-hulanda"],"_links":{"self":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts\/34478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/comments?post=34478"}],"version-history":[{"count":1,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts\/34478\/revisions"}],"predecessor-version":[{"id":34480,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts\/34478\/revisions\/34480"}],"wp:attachment":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/media?parent=34478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/categories?post=34478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/tags?post=34478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}