{"id":34350,"date":"2024-11-13T14:29:17","date_gmt":"2024-11-13T18:29:17","guid":{"rendered":"http:\/\/www.ea.aw\/pages\/?p=34350"},"modified":"2024-11-13T17:05:19","modified_gmt":"2024-11-13T21:05:19","slug":"ipa-scoge-pa-e-estudio-pa-maestro-di-ensenansa-primario","status":"publish","type":"post","link":"https:\/\/www.ea.aw\/pages\/ipa-scoge-pa-e-estudio-pa-maestro-di-ensenansa-primario\/","title":{"rendered":"IPA: Scoge pa e estudio pa Maestro di Ense\u00f1ansa Primario"},"content":{"rendered":"<p>Bo ta buscando un profesion cu ta haci impacto riba generacion actual y futuro generacion? Scoge pa e profesion maestro di Ense\u00f1ansa Primario.<\/p>\n<p><!--more--><\/p>\n<p>Como maestro bo lo crece riba tereno profesional y personal, bo lo haya satisfaccion di bo trabao y bo lo contribui na futuro di bo pais. Scoge pa e estudio pa Maestro di Ense\u00f1ansa Primario di Instituto Pedagogico Arubano (IPA) y ta e cambio!<\/p>\n<p>E estudio pa maestro di Ense\u00f1ansa Primario ta forma maestro cu ta cualifica pa duna les na mucha di scol preparatorio y\/ of scol basico: un maestro cu ta funciona competentemente den klas, na scol y den comunidad.<\/p>\n<p>Tin dos grupo di participante cu por haci e estudio pa maestro di Ense\u00f1ansa Primario:<\/p>\n<ol>\n<li>Studiante cu tin diploma di sea havo, vwo of mbo nivel 4 of si ta den examenklas di esakinan.<\/li>\n<li>Tur persona cu desde 1 di september 2025 tin minimo 21 a\u00f1a y cu kier haci un estudio na IPA, pero no tin diploma di sea havo, vwo of mbo nivel 4, por inscribi pa haci e asina yama 21+ Toets. Si bo pasa e 21+ Toets cu exito, bo ta bin na remarca pa participa na e test di admision mesun cos cu e studiantenan cu tin diploma di sea havo, vwo of mbo nivel 4.<\/li>\n<\/ol>\n<hr \/>\n<h3><span style=\"color: #333333;\">Informacion general di e estudio pa Maestro di Ense\u00f1ansa Primario<\/span><\/h3>\n<p>Tur informacion di estudio pa Maestro di Ense\u00f1ansa Primario ta riba website di IPA. Subi www.ipaaruba.com y click riba opleidingen sigui pa Leraar Primair Onderwijs. Aki lo bo haya informacion di entre otro contenido di e estudio, kico bo por haci despues di e estudio, gasto y procedura di inscripcion.<\/p>\n<hr \/>\n<h3><span style=\"color: #333333;\">Aruba College Fair 2024<\/span><\/h3>\n<p>Dia 8 y 9 di november IPA lo participa na Aruba College Fair 2024. Nos lo tey di 1 pm \u2013 7 pm na booth 49 den Renaissance Convention Center pa duna informacion y contesta tur pregunta relaciona cu e estudio pa Maestro di Ense\u00f1ansa Primario. Tambe lo tin oportunidad pa combersa cu nos studiantenan. Alabes lo por participa den algun mini actividad educacional pa experencia loke IPA tin pa ofrece.<\/p>\n<hr \/>\n<h3><span style=\"color: #333333;\">Inscripcion<\/span><\/h3>\n<p>Tur persona cu ta interesa pa haci estudio pa Maestro di Ense\u00f1ansa Primario y of e 21+ Toets por inscribi via e website <a href=\"http:\/\/www.ipaaruba.com\" target=\"_blank\" rel=\"noopener noreferrer\">ipaaruba.com<\/a>.<\/p>\n<p>Pa por inscribi mester cumpli cu e pago di AWG 80,- y pone como anexo copia di comprobante di pago den formulario digital di inscripcion. Tene na cuenta cu e comprobante mester tin bo nomber riba dje, p\u2019asina nos sa na ken e pago ta pertenece. Na final bo lo ricibi confirmacion di bo inscripcion.<\/p>\n<p>E ultimo dia pa inscribi pa 21+ Toets ta 29 di november 2024. E ultimo dia pa inscribi pa estudio pa Maestro di Ense\u00f1ansa Primario ta 1 maart 2025. Despues di e fecha aki no tin posibilidad mas pa inscribi.<\/p>\n<p>Pa keda altanto di e ultimo desaroyonan di IPA bishita <a href=\"http:\/\/www.ipaaruba.com\" target=\"_blank\" rel=\"noopener noreferrer\">ipaaruba.com<\/a> y sigui nos riba pagina di facebook Instituto Pedagogico Arubano.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium\" src=\"https:\/\/www.ea.aw\/pages\/wp-content\/uploads\/2017\/01\/ipa_logo.png\" width=\"200\" height=\"97\" \/><\/p>\n<hr \/>\n<h3><span style=\"color: #333333;\">Info \/ Contact<\/span><\/h3>\n<p>Pa mas informacion por busca den e alfabet menu riba nos pagina principal:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.ea.aw\/pages\/structura\/ensenansa-superior\/ipa\/\">[I] Instituto Pedagogico Arubano (IPA)<\/a><\/li>\n<\/ul>\n<p>Por tuma contacto cu:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.ea.aw\/pages\/contact\/scolnan-na-aruba\/ipa\/\">IPA<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Bo ta buscando un profesion cu ta haci impacto riba generacion actual y futuro generacion? Scoge pa e profesion maestro di Ense\u00f1ansa Primario.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[110,34],"class_list":["post-34350","post","type-post","status-publish","format-standard","hentry","category-news","tag-aruba","tag-ipa"],"_links":{"self":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts\/34350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/comments?post=34350"}],"version-history":[{"count":3,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts\/34350\/revisions"}],"predecessor-version":[{"id":34353,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/posts\/34350\/revisions\/34353"}],"wp:attachment":[{"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/media?parent=34350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/categories?post=34350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ea.aw\/pages\/wp-json\/wp\/v2\/tags?post=34350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}